{"id":1618,"count":10,"description":"","link":"https:\/\/koreauniversities.com\/en\/blog\/category\/life-in-korea\/","name":"Life in Korea","slug":"life-in-korea","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/koreauniversities.com\/en\/wp-json\/wp\/v2\/categories\/1618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/koreauniversities.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/koreauniversities.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/koreauniversities.com\/en\/wp-json\/wp\/v2\/posts?categories=1618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}